{"id":30633,"date":"2015-04-10T08:48:43","date_gmt":"2015-04-10T06:48:43","guid":{"rendered":"https:\/\/empresas.infoempleo.com\/hrtrends\/?p=30633"},"modified":"2018-05-23T16:55:10","modified_gmt":"2018-05-23T14:55:10","slug":"retribucion-flexible-mejorar-salario-tus-empleados","status":"publish","type":"post","link":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/","title":{"rendered":"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados"},"content":{"rendered":"<p>Con los a\u00f1os, la gesti\u00f3n de las personas ha dejado de ser un asunto administrativo, para convertirse en una cuesti\u00f3n de alcance estrat\u00e9gico. Tener en cuenta la opini\u00f3n de los empleados, implementar iniciativas para promover su participaci\u00f3n en la empresa y sumar a la consecuci\u00f3n del equilibrio entre el plano personal y el profesional, se han convertido en competencias de las compa\u00f1\u00edas y han dado lugar a nuevas formas de compensaci\u00f3n que pueden transformar las condiciones laborales.<\/p>\n<p>En el escenario de las nuevas <strong>f\u00f3rmulas de compensaci\u00f3n laboral<\/strong> se han hecho con un sitio en primera fila los planes de retribuci\u00f3n flexible, avalados por una impecable carta de presentaci\u00f3n que los describe como <strong>herramientas eficaces<\/strong> para optimizar la retribuci\u00f3n de los empleados.<\/p>\n<p>Y es cierto que si pensamos en un plan capaz de convertir una parte del salario en un seguro m\u00e9dico, guarder\u00eda, transporte, gasolina\u2026, <strong>ahorrando impuestos<\/strong> al mismo tiempo, lo de optimizar la retribuci\u00f3n de los empleados se quedar\u00eda corto.<\/p>\n<p>Hoy en d\u00eda, los planes de retribuci\u00f3n flexible consisten en eso, en <strong>intercambiar salario en efectivo por productos o servicios<\/strong> que la empresa pone a disposici\u00f3n de sus empleados. Es el trabajador el que est\u00e1 pagando esos productos, pero las ventajas fiscales, la comodidad de contrataci\u00f3n, y la conciliaci\u00f3n familiar que muchos de estos servicios llevan en el ADN han conseguido que ganen popularidad, aumentando, adem\u00e1s, el grado de satisfacci\u00f3n de los empleados.<\/p>\n<p>Sin embargo, todav\u00eda son muchas las dudas que rodean la retribuci\u00f3n flexible en nuestro pa\u00eds, donde sigue siendo una asignatura pendiente por parte de la mayor\u00eda de las compa\u00f1\u00edas. En este contexto, y bajo la Iniciativa CRECE : Ideas y Networking, que ofrece encuentros de debate para responsables y directivos de organizaciones, <strong>Madrid acoge \u00a0la jornada \u201cRetribuci\u00f3n Flexible, c\u00f3mo mejorar el salario de tus empleados\u201d<\/strong>.<\/p>\n<p>Un encuentro tuvo lugar <strong>el 16 de abril en la Academia de las Artes y las Ciencias Cinematogr\u00e1ficas<\/strong> y en \u00e9l se ofrecieron las claves para mejorar el sueldo sin ampliar los costes, las consideraciones fiscales y laborales del R.D. 16\/2013 y un caso pr\u00e1ctico de implantaci\u00f3n de un sistema de retribuci\u00f3n flexible.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con los a\u00f1os, la gesti\u00f3n de las personas ha dejado de ser un asunto administrativo, para convertirse en<a class=\"moretag\" href=\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/\"> Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":72,"featured_media":30634,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3035],"tags":[1915,449,70,223],"class_list":["post-30633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos","tag-retribucion-flexible","tag-retribuciones","tag-rrhh","tag-salarios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados | HRTRENDS<\/title>\n<meta name=\"description\" content=\"En el escenario de las nuevas f\u00f3rmulas de compensaci\u00f3n laboral se han hecho con un sitio en primera fila los planes de retribuci\u00f3n flexible. \u00a1Con\u00f3celo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados | HRTRENDS\" \/>\n<meta property=\"og:description\" content=\"En el escenario de las nuevas f\u00f3rmulas de compensaci\u00f3n laboral se han hecho con un sitio en primera fila los planes de retribuci\u00f3n flexible. \u00a1Con\u00f3celo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/\" \/>\n<meta property=\"og:site_name\" content=\"HRTRENDS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoempleo\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-10T06:48:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-23T14:55:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"722\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"infoempleo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoempleo\" \/>\n<meta name=\"twitter:site\" content=\"@infoempleo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"infoempleo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/\"},\"author\":{\"name\":\"infoempleo\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/67d3e276ffcc8b3ae0ebec816daf775a\"},\"headline\":\"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados\",\"datePublished\":\"2015-04-10T06:48:43+00:00\",\"dateModified\":\"2018-05-23T14:55:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368.jpg\",\"keywords\":[\"retribuci\u00f3n flexible\",\"retribuciones\",\"RRHH\",\"salarios\"],\"articleSection\":[\"Consejos\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/\",\"name\":\"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados | HRTRENDS\",\"isPartOf\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368.jpg\",\"datePublished\":\"2015-04-10T06:48:43+00:00\",\"dateModified\":\"2018-05-23T14:55:10+00:00\",\"description\":\"En el escenario de las nuevas f\u00f3rmulas de compensaci\u00f3n laboral se han hecho con un sitio en primera fila los planes de retribuci\u00f3n flexible. \u00a1Con\u00f3celo!\",\"breadcrumb\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#primaryimage\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368-150x150.jpg\",\"contentUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368-150x150.jpg\",\"width\":150,\"height\":150,\"caption\":\"C\u00f3mo pagar a los empleados\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#website\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\",\"name\":\"HRTrends by Infoempleo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"},\"potentialAction\":{\"@type\":\"SearchAction\",\"target\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\",\"name\":\"Infoempleo\",\"url\":\"https:\/\/www.infoempleo.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg\",\"contentUrl\":\"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg\",\"width\":150,\"height\":40,\"caption\":\"Infoempleo\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Infoempleo\",\"https:\/\/x.com\/infoempleo\",\"http:\/\/instagram.com\/infoempleo\/\",\"http:\/\/www.linkedin.com\/groups\/Empleo-Espa\u00f1a-Infoempleocom-111276\",\"http:\/\/pinterest.com\/infoempleo\/\"],\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Madrid\",\"postalCode\":\"28050\",\"streetAddress\":\"Avenida de Burgos 114\"},\"brand\":[\"Infoempleo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/67d3e276ffcc8b3ae0ebec816daf775a\",\"name\":\"infoempleo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b437777242fe67d2473c2a818da2344692d1ee91e91080ccffbd97bcd4a0975?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b437777242fe67d2473c2a818da2344692d1ee91e91080ccffbd97bcd4a0975?s=96&d=mm&r=g\",\"caption\":\"infoempleo\"},\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/author\/infoempleo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados | HRTRENDS","description":"En el escenario de las nuevas f\u00f3rmulas de compensaci\u00f3n laboral se han hecho con un sitio en primera fila los planes de retribuci\u00f3n flexible. \u00a1Con\u00f3celo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/","og_locale":"es_ES","og_type":"article","og_title":"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados | HRTRENDS","og_description":"En el escenario de las nuevas f\u00f3rmulas de compensaci\u00f3n laboral se han hecho con un sitio en primera fila los planes de retribuci\u00f3n flexible. \u00a1Con\u00f3celo!","og_url":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/","og_site_name":"HRTRENDS","article_publisher":"https:\/\/www.facebook.com\/Infoempleo","article_published_time":"2015-04-10T06:48:43+00:00","article_modified_time":"2018-05-23T14:55:10+00:00","og_image":[{"width":722,"height":484,"url":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368.jpg","type":"image\/jpeg"}],"author":"infoempleo","twitter_card":"summary_large_image","twitter_creator":"@infoempleo","twitter_site":"@infoempleo","twitter_misc":{"Escrito por":"infoempleo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#article","isPartOf":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/"},"author":{"name":"infoempleo","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/67d3e276ffcc8b3ae0ebec816daf775a"},"headline":"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados","datePublished":"2015-04-10T06:48:43+00:00","dateModified":"2018-05-23T14:55:10+00:00","mainEntityOfPage":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/"},"wordCount":398,"publisher":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#primaryimage"},"thumbnailUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368.jpg","keywords":["retribuci\u00f3n flexible","retribuciones","RRHH","salarios"],"articleSection":["Consejos"],"inLanguage":"es","copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"}},{"@type":"WebPage","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/","url":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/","name":"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados | HRTRENDS","isPartOf":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#website"},"primaryImageOfPage":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#primaryimage"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#primaryimage"},"thumbnailUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368.jpg","datePublished":"2015-04-10T06:48:43+00:00","dateModified":"2018-05-23T14:55:10+00:00","description":"En el escenario de las nuevas f\u00f3rmulas de compensaci\u00f3n laboral se han hecho con un sitio en primera fila los planes de retribuci\u00f3n flexible. \u00a1Con\u00f3celo!","breadcrumb":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#primaryimage","url":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368-150x150.jpg","contentUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2017\/06\/ThinkstockPhotos-615104368-150x150.jpg","width":150,"height":150,"caption":"C\u00f3mo pagar a los empleados"},{"@type":"BreadcrumbList","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/retribucion-flexible-mejorar-salario-tus-empleados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/empresas.infoempleo.com\/hrtrends\/"},{"@type":"ListItem","position":2,"name":"Retribuci\u00f3n flexible o c\u00f3mo mejorar el salario de tus empleados"}]},{"@type":"WebSite","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#website","url":"https:\/\/empresas.infoempleo.com\/hrtrends","name":"HRTrends by Infoempleo","description":"","publisher":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"},"potentialAction":{"@type":"SearchAction","target":"https:\/\/empresas.infoempleo.com\/hrtrends\/?s={search_term_string}","query-input":"required name=search_term_string"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization","name":"Infoempleo","url":"https:\/\/www.infoempleo.com\/","logo":{"@type":"ImageObject","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo","inLanguage":"es","url":"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg","contentUrl":"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg","width":150,"height":40,"caption":"Infoempleo"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo"},"sameAs":["https:\/\/www.facebook.com\/Infoempleo","https:\/\/x.com\/infoempleo","http:\/\/instagram.com\/infoempleo\/","http:\/\/www.linkedin.com\/groups\/Empleo-Espa\u00f1a-Infoempleocom-111276","http:\/\/pinterest.com\/infoempleo\/"],"address":{"@type":"PostalAddress","addressLocality":"Madrid","postalCode":"28050","streetAddress":"Avenida de Burgos 114"},"brand":["Infoempleo"]},{"@type":"Person","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/67d3e276ffcc8b3ae0ebec816daf775a","name":"infoempleo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b437777242fe67d2473c2a818da2344692d1ee91e91080ccffbd97bcd4a0975?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b437777242fe67d2473c2a818da2344692d1ee91e91080ccffbd97bcd4a0975?s=96&d=mm&r=g","caption":"infoempleo"},"url":"https:\/\/empresas.infoempleo.com\/hrtrends\/author\/infoempleo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts\/30633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/comments?post=30633"}],"version-history":[{"count":0,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts\/30633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/media\/30634"}],"wp:attachment":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/media?parent=30633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/categories?post=30633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/tags?post=30633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}