{"id":2167,"date":"2013-01-21T09:00:05","date_gmt":"2013-01-21T07:00:05","guid":{"rendered":"http:\/\/blog.infoempleo.com\/?p=2167"},"modified":"2019-01-04T10:58:47","modified_gmt":"2019-01-04T08:58:47","slug":"la-libertad-al-empleado-clave-del-exito-empresarial","status":"publish","type":"post","link":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/","title":{"rendered":"La libertad al empleado, clave del \u00e9xito empresarial"},"content":{"rendered":"<p>Richard Branson es sin\u00f3nimo de \u00e9xito empresarial. En los \u00faltimos 30 a\u00f1os, el brit\u00e1nico ha fundado bajo el nombre de Virgin una compa\u00f1\u00eda de discos, unas aerol\u00edneas, una emisora de radio, una gama de refrescos de cola y una empresa de telefon\u00eda m\u00f3vil. Es para muchos un gur\u00fa de los negocios y sus consejos se publican en revistas como Entrepreneur, donde confiesa que gran parte de sus logros se debe a la libertad y confianza que deposita en sus trabajadores.<\/p>\n<p><!--more-->A la hora de explicar la eficiencia de muchas de sus empresas, Branson destaca la libertad que da a sus empleados como una de las claves que \u00e9l como empresario considera que debe cumplir, aunque es consciente de que es una norma que desaf\u00eda una ley que hasta ahora parec\u00eda b\u00e1sica para cualquier compa\u00f1\u00eda de cierto tama\u00f1o. \u201cSiempre he trabajado para m\u00ed mismo, sin tener que jugar con las reglas de otro. Desde los primeros d\u00edas que trabaj\u00e9 en construir Virgin me propuse que mis empleados disfrutaran de esa clase de libertad que yo he tenido\u201d, dice en la edici\u00f3n online de la publicaci\u00f3n.<\/p>\n<p>Una de las grandezas de un profesional reside en conocer sus limitaciones. Su compa\u00f1\u00eda multinacional se ha expandido en 2012 en lugares tan dispares como Chile o Polonia y \u00e9l, consciente de la imposibilidad de entender y conocer el mercado y al cliente de cada pa\u00eds, cede total autonom\u00eda a sus equipos de trabajo una vez que se les ha contratado y se ha asegurado de transmitir a sus nuevos CEO\u00b4s y empleados los pilares fundamentales que definen a la empresa, entre ellos, no obligarles a cumplir con unos objetivos inmediatos para que as\u00ed puedan tomar m\u00e1s riesgos.<\/p>\n<p>Esa libertad de movimientos que los empleados comparten con los directivos, dice el magnate, es la que ha llevado a las empresas del grupo \u201ca llegar donde otras no pueden\u201d y pone como ejemplo <span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.virgingalactic.com\/\">Virgin Galactic<\/a><\/span><\/span>, compa\u00f1\u00eda de turismo que programa viajes al espacio. \u201cEsta pol\u00edtica que llevamos ayuda a nuestros trabajadores a perseguir sus pasiones\u201d, apunta como otra causa de \u00e9xito.<\/p>\n<p>El millonario es consciente de que su consejo puede que no sirva para todo el mundo, pero reconoce que lo ha aplicado a todos sus proyectos y siempre ha funcionado. Por eso cree que as\u00ed ocurrir\u00e1 con cualquier otra futura idea, \u201csea un banco o una empresa de servicios m\u00e9dicos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Richard Branson es sin\u00f3nimo de \u00e9xito empresarial. En los \u00faltimos 30 a\u00f1os, el brit\u00e1nico ha fundado bajo el<a class=\"moretag\" href=\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/\"> Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":8,"featured_media":29622,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1049,358,359,360,361],"class_list":["post-2167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-empleados","tag-exito-empresarial","tag-libertad","tag-richard-branson","tag-virgin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La libertad al empleado, clave del \u00e9xito empresarial | HRTRENDS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La libertad al empleado, clave del \u00e9xito empresarial | HRTRENDS\" \/>\n<meta property=\"og:description\" content=\"Richard Branson es sin\u00f3nimo de \u00e9xito empresarial. En los \u00faltimos 30 a\u00f1os, el brit\u00e1nico ha fundado bajo el Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/\" \/>\n<meta property=\"og:site_name\" content=\"HRTRENDS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoempleo\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-21T07:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-04T08:58:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hector\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoempleo\" \/>\n<meta name=\"twitter:site\" content=\"@infoempleo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hector\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/\"},\"author\":{\"name\":\"hector\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/9d10391fb925db910b931e32a016b524\"},\"headline\":\"La libertad al empleado, clave del \u00e9xito empresarial\",\"datePublished\":\"2013-01-21T07:00:05+00:00\",\"dateModified\":\"2019-01-04T08:58:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/\"},\"wordCount\":423,\"publisher\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave.jpeg\",\"keywords\":[\"empleados\",\"\u00e9xito empresarial\",\"Libertad\",\"Richard Branson\",\"Virgin\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2013\",\"copyrightHolder\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/\",\"name\":\"La libertad al empleado, clave del \u00e9xito empresarial | HRTRENDS\",\"isPartOf\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave.jpeg\",\"datePublished\":\"2013-01-21T07:00:05+00:00\",\"dateModified\":\"2019-01-04T08:58:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#primaryimage\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave-150x150.jpeg\",\"contentUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave-150x150.jpeg\",\"width\":150,\"height\":150,\"caption\":\"Dar libertad al empleado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La libertad al empleado, clave del \u00e9xito empresarial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#website\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\",\"name\":\"HRTrends by Infoempleo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"},\"potentialAction\":{\"@type\":\"SearchAction\",\"target\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\",\"name\":\"Infoempleo\",\"url\":\"https:\/\/www.infoempleo.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg\",\"contentUrl\":\"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg\",\"width\":150,\"height\":40,\"caption\":\"Infoempleo\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Infoempleo\",\"https:\/\/x.com\/infoempleo\",\"http:\/\/instagram.com\/infoempleo\/\",\"http:\/\/www.linkedin.com\/groups\/Empleo-Espa\u00f1a-Infoempleocom-111276\",\"http:\/\/pinterest.com\/infoempleo\/\"],\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Madrid\",\"postalCode\":\"28050\",\"streetAddress\":\"Avenida de Burgos 114\"},\"brand\":[\"Infoempleo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/9d10391fb925db910b931e32a016b524\",\"name\":\"hector\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/32a196a421fde48c7ac739e500e18223e150407b031d2cf2a82bfdfc9ca62027?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/32a196a421fde48c7ac739e500e18223e150407b031d2cf2a82bfdfc9ca62027?s=96&d=mm&r=g\",\"caption\":\"hector\"},\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/author\/hector\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La libertad al empleado, clave del \u00e9xito empresarial | HRTRENDS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/","og_locale":"es_ES","og_type":"article","og_title":"La libertad al empleado, clave del \u00e9xito empresarial | HRTRENDS","og_description":"Richard Branson es sin\u00f3nimo de \u00e9xito empresarial. En los \u00faltimos 30 a\u00f1os, el brit\u00e1nico ha fundado bajo el Leer m\u00e1s","og_url":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/","og_site_name":"HRTRENDS","article_publisher":"https:\/\/www.facebook.com\/Infoempleo","article_published_time":"2013-01-21T07:00:05+00:00","article_modified_time":"2019-01-04T08:58:47+00:00","og_image":[{"width":1125,"height":750,"url":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave.jpeg","type":"image\/jpeg"}],"author":"hector","twitter_card":"summary_large_image","twitter_creator":"@infoempleo","twitter_site":"@infoempleo","twitter_misc":{"Escrito por":"hector","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#article","isPartOf":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/"},"author":{"name":"hector","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/9d10391fb925db910b931e32a016b524"},"headline":"La libertad al empleado, clave del \u00e9xito empresarial","datePublished":"2013-01-21T07:00:05+00:00","dateModified":"2019-01-04T08:58:47+00:00","mainEntityOfPage":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/"},"wordCount":423,"publisher":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave.jpeg","keywords":["empleados","\u00e9xito empresarial","Libertad","Richard Branson","Virgin"],"articleSection":["Actualidad"],"inLanguage":"es","copyrightYear":"2013","copyrightHolder":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"}},{"@type":"WebPage","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/","url":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/","name":"La libertad al empleado, clave del \u00e9xito empresarial | HRTRENDS","isPartOf":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#website"},"primaryImageOfPage":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#primaryimage"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave.jpeg","datePublished":"2013-01-21T07:00:05+00:00","dateModified":"2019-01-04T08:58:47+00:00","breadcrumb":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#primaryimage","url":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave-150x150.jpeg","contentUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/candado-llave-150x150.jpeg","width":150,"height":150,"caption":"Dar libertad al empleado"},{"@type":"BreadcrumbList","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/la-libertad-al-empleado-clave-del-exito-empresarial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/empresas.infoempleo.com\/hrtrends\/"},{"@type":"ListItem","position":2,"name":"La libertad al empleado, clave del \u00e9xito empresarial"}]},{"@type":"WebSite","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#website","url":"https:\/\/empresas.infoempleo.com\/hrtrends","name":"HRTrends by Infoempleo","description":"","publisher":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"},"potentialAction":{"@type":"SearchAction","target":"https:\/\/empresas.infoempleo.com\/hrtrends\/?s={search_term_string}","query-input":"required name=search_term_string"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization","name":"Infoempleo","url":"https:\/\/www.infoempleo.com\/","logo":{"@type":"ImageObject","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo","inLanguage":"es","url":"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg","contentUrl":"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg","width":150,"height":40,"caption":"Infoempleo"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo"},"sameAs":["https:\/\/www.facebook.com\/Infoempleo","https:\/\/x.com\/infoempleo","http:\/\/instagram.com\/infoempleo\/","http:\/\/www.linkedin.com\/groups\/Empleo-Espa\u00f1a-Infoempleocom-111276","http:\/\/pinterest.com\/infoempleo\/"],"address":{"@type":"PostalAddress","addressLocality":"Madrid","postalCode":"28050","streetAddress":"Avenida de Burgos 114"},"brand":["Infoempleo"]},{"@type":"Person","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/9d10391fb925db910b931e32a016b524","name":"hector","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/32a196a421fde48c7ac739e500e18223e150407b031d2cf2a82bfdfc9ca62027?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32a196a421fde48c7ac739e500e18223e150407b031d2cf2a82bfdfc9ca62027?s=96&d=mm&r=g","caption":"hector"},"url":"https:\/\/empresas.infoempleo.com\/hrtrends\/author\/hector\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts\/2167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/comments?post=2167"}],"version-history":[{"count":0,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts\/2167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/media\/29622"}],"wp:attachment":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/media?parent=2167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/categories?post=2167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/tags?post=2167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}