{"id":15980,"date":"2013-01-08T12:55:56","date_gmt":"2013-01-08T11:55:56","guid":{"rendered":"http:\/\/blog.infoempleo.com\/?p=15980"},"modified":"2024-08-29T17:46:55","modified_gmt":"2024-08-29T15:46:55","slug":"las-nuevas-tecnologias-clave-creciente-del-mercado-laboral","status":"publish","type":"post","link":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/","title":{"rendered":"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral"},"content":{"rendered":"<p>La \u00faltima edici\u00f3n de la Feria OFITEC (Sal\u00f3n Profesional Internacional de Equipamiento de Oficinas y Colectividades) ofreci\u00f3 un panorama amplio de hacia d\u00f3nde van los entornos profesionales de las pr\u00f3ximas d\u00e9cadas. Por ejemplo, se detect\u00f3 una <strong>tendencia en reducir el mobiliario de almacenamiento por la generalizaci\u00f3n de archivos digitales; el desarrollo de reuniones virtuales; la proliferaci\u00f3n de piezas modulables,\u00a0que ahorran espacio y permiten modificar las estancias seg\u00fan la necesidad; o la integraci\u00f3n del mobiliario de trabajo en el hogar para facilitar la flexibilidad laboral<\/strong>.<\/p>\n<p>Se present\u00f3 tambi\u00e9n el llamado proceso de Dise\u00f1o Amodo, creado por <strong>Quim Larrea, director del Centro Tecnol\u00f3gico Andaluz de Dise\u00f1o, Surgenia<\/strong>. <strong>Se trata de un nuevo puesto de trabajo m\u00f3vil, interactivo y adaptado a las necesidades de los usuarios<\/strong>, incluidos los discapacitados, que de alg\u00fan modo adelanta lo que puede ser la oficina del futuro. Todas estas soluciones, que hace unos a\u00f1os pertenec\u00edan a la ciencia ficci\u00f3n, se han convertido en realidades que van a configurar el espacio laboral del futuro. La clave son las nuevas tecnolog\u00edas.<\/p>\n<p>Y es que tal como indica el informe <a href=\"https:\/\/www.clubsostenibilidad.org\/main.asp?id_pagina=33\" target=\"_blank\" rel=\"noopener\">\u2018Spain 20.20\u2019<\/a>, elaborado por el Club de Excelencia en Sostenibilidad en colaboraci\u00f3n con diez \u2018partners\u2019 empresariales \u2013ABB, Accenture, Endesa, Ericsson, Holcim, MRW, Orange, REE, T Systems y Vodafone\u2013, <strong>las tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n (TIC) permitir\u00e1n reducir gastos y mejorar la calidad de los servicios.<\/strong> La implantaci\u00f3n de las TIC en sectores transversales de la econom\u00eda puede llegar a suponer, hasta el a\u00f1o 2020, un ahorro potencial neto acumulado de m\u00e1s de 600.000 millones de euros, a los que se a\u00f1adir\u00edan unos 65.000 millones de ingresos extra mediante la creaci\u00f3n de nuevos negocios.<\/p>\n<p>Todo ello supondr\u00eda la <strong>creaci\u00f3n potencial de 218.000 empleos en Espa\u00f1a<\/strong>. \u00abNo solo nuevos empleos, sino mayor calidad de empleo, estabilidad, flexibilidad e igualdad de oportunidades, integraci\u00f3n social o calidad de vida, son algunos de los potenciales beneficios sociales que conlleva la implantaci\u00f3n de las TIC, gracias al teletrabajo, el \u2018e-learning\u2019 o la teleasistencia\u00bb, se\u00f1alan desde el Club de Excelencia en Sostenibilidad. Desde el \u00a0junto de vista medioambiental, la aplicaci\u00f3n de las TIC de forma masiva y transversal a diferentes sectores productivos conlleva mejoras de eficiencia, que llevan aparejada la reducci\u00f3n potencial de hasta 36,76 millones de toneladas de CO2, alcanzado en 2020 cifras de 388,40 millones de toneladas de CO2.<\/p>\n<h3>Con los cinco sentidos<\/h3>\n<p><a href=\"https:\/\/www.ibm.com\/es-es\" target=\"_blank\" rel=\"noopener\">IBM<\/a> acaba de publicar sus previsiones \u20185 en 5\u2019. Cada diciembre, desde 2006, la compa\u00f1\u00eda da a conocer cinco\u00a0cuestiones del mundo de la innovaci\u00f3n y la tecnolog\u00eda que van a cambiar nuestra forma de trabajar y vivir en los pr\u00f3ximos cinco a\u00f1os. <strong>Las previsiones de este a\u00f1o se centran en un elemento nuevo de la pr\u00f3xima era de la computaci\u00f3n, el de los \u00absistemas cognitivos\u00bb, basada en la habilidad de los ordenadores para imitar a su manera los sentidos humanos.<\/strong><\/p>\n<p>Seg\u00fan Robyn Schwartz, experta en la industria \u2018retail\u2019 \u00a0de IBM, \u00abdentro de cinco a\u00f1os podremos tocar a trav\u00e9s de nuestro m\u00f3vil\u00bb. Esta tecnolog\u00eda puede tener aplicaciones en el sector sanitario \u2013los m\u00e9dicos podr\u00e1n \u00a0examinar en remoto y de forma t\u00e1ctil a los pacientes\u2013 o en la industria manufacturera.<\/p>\n<p>En cuanto al sentido de la vista, los ordenadores, en cinco a\u00f1os, podr\u00e1n reconocer im\u00e1genes e interpretarlas, una capacidad que ser\u00e1 muy \u00fatil en la industria del comercio o el m\u00e1rketing, ya que las empresas podr\u00e1n ofrecer \u00a0productos o servicios individualizados dependiendo de las fotos que compartamos en internet. En referencia al gusto, los ingenieros habr\u00e1n creado papilas gustativas digitales que nos ayudar\u00e1n a comer de forma m\u00e1s \u00a0inteligente. \u00a0Se podr\u00e1n desarrollar, por ejemplo, p\u00e1ginas web con recomendaciones nutricionales basadas en nuestros historiales m\u00e9dicos.<\/p>\n<p>Y tambi\u00e9n en cinco a\u00f1os, \u00a0los ordenadores contar\u00e1n con el sentido del olfato, seg\u00fan los expertos de IBM, un avance que servir\u00e1, por ejemplo, para detectar focos de infecci\u00f3n. Por \u00faltimo, los ordenadores tambi\u00e9n \u2018escuchar\u00e1n\u2019 qu\u00e9 est\u00e1 pasando. Los investigadores de la firma creen que esta tecnolog\u00eda podr\u00eda usarse en la industria de los transportes, ya que se podr\u00edan detectar movimientos s\u00edsmicos o meteorol\u00f3gicos.<\/p>\n<h3>Adi\u00f3s a los \u2018e-mails\u2019<\/h3>\n<p>El informe <a href=\"https:\/\/portal.eiu.com\/login.aspx?service=https:\/\/www.eiu.com&amp;brand=&amp;clientid=750s8at17s32q&amp;gateway=true&amp;returnto=https%3a%2f%2fwww.eiu.com%2findex.asp%3f%26\" target=\"_blank\" rel=\"noopener\" class=\"broken_link\">\u2018Economist Intelligence Unit\u2019<\/a>, realizado por este conocido medio brit\u00e1nico, ofrece tambi\u00e9n una visi\u00f3n de lo que ser\u00e1 el futuro de los entornos laborales. El documento concluye que el cambio tecnol\u00f3gico se producir\u00e1 de la mano de <strong>cuatro nuevas tendencias: el \u2018cloud computing\u2019, el \u2018big data\u2019, la videocomunicaci\u00f3n y la movilidad<\/strong>. As\u00ed, por ejemplo, en \u00a02020 se reducir\u00e1 el tr\u00e1fico de correos electr\u00f3nicos debido a la irrupci\u00f3n de las videoconferencias, que ser\u00e1n el medio m\u00e1s com\u00fan de comunicaci\u00f3n, junto a las redes sociales corporativas. Adem\u00e1s, los micro emprendedores ganar\u00e1n terreno a las medianas empresas en una d\u00e9cada, ya que los avances tecnol\u00f3gicos permitir\u00e1n que estas peque\u00f1as empresas operen como si fueran mucho m\u00e1s grandes.<\/p>\n<p><strong>El estudio tambi\u00e9n sostiene que la tecnolog\u00eda traer\u00e1 m\u00e1s flexibilidad y movilidad, aunque, por el contrario, propiciar\u00e1 la destrucci\u00f3n de empleo, la desaparici\u00f3n de algunas profesiones, una vida laboral m\u00e1s larga e incluso la \u2018no desconexi\u00f3n\u2019 entre el trabajo y la vida personal.<\/strong> Es un punto de vista que comparten desde la consultora <a href=\"https:\/\/www.adecco.es\/\" target=\"_blank\" rel=\"noopener\">Adecco<\/a>, que tambi\u00e9n creen que las actividades repetitivas y rutinarias, que demandan solo cualificaciones medias, ser\u00e1n mayoritariamente automatizadas, dejando obsoleta la formaci\u00f3n de muchos de los trabajadores. Por eso, en este panorama, los trabajadores m\u00e1s cualificados se ver\u00e1n beneficiados por la \u00a0introducci\u00f3n de nuevas\u00a0tecnolog\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00faltima edici\u00f3n de la Feria OFITEC (Sal\u00f3n Profesional Internacional de Equipamiento de Oficinas y Colectividades) ofreci\u00f3 un<a class=\"moretag\" href=\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/\"> Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":50,"featured_media":15981,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[162,1849,198,510],"class_list":["post-15980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-empleo","tag-evolucion","tag-innovacion","tag-nuevas-tecnologias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las nuevas tecnolog\u00edas, clave creciente del mercado laboral | HRTRENDS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral | HRTRENDS\" \/>\n<meta property=\"og:description\" content=\"La \u00faltima edici\u00f3n de la Feria OFITEC (Sal\u00f3n Profesional Internacional de Equipamiento de Oficinas y Colectividades) ofreci\u00f3 un Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/\" \/>\n<meta property=\"og:site_name\" content=\"HRTRENDS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoempleo\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-08T11:55:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T15:46:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"556\" \/>\n\t<meta property=\"og:image:height\" content=\"258\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Mu\u00f1oz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infoempleo\" \/>\n<meta name=\"twitter:site\" content=\"@infoempleo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Mu\u00f1oz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/\"},\"author\":{\"name\":\"Sergio Mu\u00f1oz\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/6eed0717dd6d324ad674543577f7d352\"},\"headline\":\"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral\",\"datePublished\":\"2013-01-08T11:55:56+00:00\",\"dateModified\":\"2024-08-29T15:46:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/\"},\"wordCount\":993,\"publisher\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias.jpg\",\"keywords\":[\"Empleo\",\"evoluci\u00f3n\",\"innovaci\u00f3n\",\"nuevas tecnolog\u00edas\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2013\",\"copyrightHolder\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/\",\"name\":\"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral | HRTRENDS\",\"isPartOf\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias.jpg\",\"datePublished\":\"2013-01-08T11:55:56+00:00\",\"dateModified\":\"2024-08-29T15:46:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#primaryimage\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias-150x150.jpg\",\"contentUrl\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias-150x150.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#website\",\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\",\"name\":\"HRTrends by Infoempleo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\"},\"potentialAction\":{\"@type\":\"SearchAction\",\"target\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization\",\"name\":\"Infoempleo\",\"url\":\"https:\/\/www.infoempleo.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg\",\"contentUrl\":\"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg\",\"width\":150,\"height\":40,\"caption\":\"Infoempleo\"},\"image\":{\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Infoempleo\",\"https:\/\/x.com\/infoempleo\",\"http:\/\/instagram.com\/infoempleo\/\",\"http:\/\/www.linkedin.com\/groups\/Empleo-Espa\u00f1a-Infoempleocom-111276\",\"http:\/\/pinterest.com\/infoempleo\/\"],\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Madrid\",\"postalCode\":\"28050\",\"streetAddress\":\"Avenida de Burgos 114\"},\"brand\":[\"Infoempleo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/6eed0717dd6d324ad674543577f7d352\",\"name\":\"Sergio Mu\u00f1oz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e7731161b4b74cbcb9baea8553044aadfdf78c0164ca104016474818fd843019?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e7731161b4b74cbcb9baea8553044aadfdf78c0164ca104016474818fd843019?s=96&d=mm&r=g\",\"caption\":\"Sergio Mu\u00f1oz\"},\"url\":\"https:\/\/empresas.infoempleo.com\/hrtrends\/author\/sergio-munoz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral | HRTRENDS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/","og_locale":"es_ES","og_type":"article","og_title":"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral | HRTRENDS","og_description":"La \u00faltima edici\u00f3n de la Feria OFITEC (Sal\u00f3n Profesional Internacional de Equipamiento de Oficinas y Colectividades) ofreci\u00f3 un Leer m\u00e1s","og_url":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/","og_site_name":"HRTRENDS","article_publisher":"https:\/\/www.facebook.com\/Infoempleo","article_published_time":"2013-01-08T11:55:56+00:00","article_modified_time":"2024-08-29T15:46:55+00:00","og_image":[{"width":556,"height":258,"url":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias.jpg","type":"image\/jpeg"}],"author":"Sergio Mu\u00f1oz","twitter_card":"summary_large_image","twitter_creator":"@infoempleo","twitter_site":"@infoempleo","twitter_misc":{"Escrito por":"Sergio Mu\u00f1oz","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#article","isPartOf":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/"},"author":{"name":"Sergio Mu\u00f1oz","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/6eed0717dd6d324ad674543577f7d352"},"headline":"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral","datePublished":"2013-01-08T11:55:56+00:00","dateModified":"2024-08-29T15:46:55+00:00","mainEntityOfPage":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/"},"wordCount":993,"publisher":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#primaryimage"},"thumbnailUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias.jpg","keywords":["Empleo","evoluci\u00f3n","innovaci\u00f3n","nuevas tecnolog\u00edas"],"articleSection":["Actualidad"],"inLanguage":"es","copyrightYear":"2013","copyrightHolder":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"}},{"@type":"WebPage","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/","url":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/","name":"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral | HRTRENDS","isPartOf":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#website"},"primaryImageOfPage":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#primaryimage"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#primaryimage"},"thumbnailUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias.jpg","datePublished":"2013-01-08T11:55:56+00:00","dateModified":"2024-08-29T15:46:55+00:00","breadcrumb":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#primaryimage","url":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias-150x150.jpg","contentUrl":"https:\/\/empresas.infoempleo.com\/hrtrends\/media\/2013\/01\/Tecnologias-150x150.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/las-nuevas-tecnologias-clave-creciente-del-mercado-laboral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/empresas.infoempleo.com\/hrtrends\/"},{"@type":"ListItem","position":2,"name":"Las nuevas tecnolog\u00edas, clave creciente del mercado laboral"}]},{"@type":"WebSite","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#website","url":"https:\/\/empresas.infoempleo.com\/hrtrends","name":"HRTrends by Infoempleo","description":"","publisher":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization"},"potentialAction":{"@type":"SearchAction","target":"https:\/\/empresas.infoempleo.com\/hrtrends\/?s={search_term_string}","query-input":"required name=search_term_string"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#organization","name":"Infoempleo","url":"https:\/\/www.infoempleo.com\/","logo":{"@type":"ImageObject","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo","inLanguage":"es","url":"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg","contentUrl":"https:\/\/cdnazure.infoempleo.com\/infoempleo\/assets\/style\/gfx\/logo.svg","width":150,"height":40,"caption":"Infoempleo"},"image":{"@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#logo"},"sameAs":["https:\/\/www.facebook.com\/Infoempleo","https:\/\/x.com\/infoempleo","http:\/\/instagram.com\/infoempleo\/","http:\/\/www.linkedin.com\/groups\/Empleo-Espa\u00f1a-Infoempleocom-111276","http:\/\/pinterest.com\/infoempleo\/"],"address":{"@type":"PostalAddress","addressLocality":"Madrid","postalCode":"28050","streetAddress":"Avenida de Burgos 114"},"brand":["Infoempleo"]},{"@type":"Person","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/6eed0717dd6d324ad674543577f7d352","name":"Sergio Mu\u00f1oz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/empresas.infoempleo.com\/hrtrends\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e7731161b4b74cbcb9baea8553044aadfdf78c0164ca104016474818fd843019?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7731161b4b74cbcb9baea8553044aadfdf78c0164ca104016474818fd843019?s=96&d=mm&r=g","caption":"Sergio Mu\u00f1oz"},"url":"https:\/\/empresas.infoempleo.com\/hrtrends\/author\/sergio-munoz\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts\/15980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/comments?post=15980"}],"version-history":[{"count":2,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts\/15980\/revisions"}],"predecessor-version":[{"id":45162,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/posts\/15980\/revisions\/45162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/media\/15981"}],"wp:attachment":[{"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/media?parent=15980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/categories?post=15980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/empresas.infoempleo.com\/hrtrends\/wp-json\/wp\/v2\/tags?post=15980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}